{"id":264130,"date":"2026-07-09T19:52:44","date_gmt":"2026-07-09T17:52:44","guid":{"rendered":"https:\/\/www.ferberpainting.com\/us\/how-to-strip-copper-the-complete-guide\/"},"modified":"2026-07-09T19:52:44","modified_gmt":"2026-07-09T17:52:44","slug":"how-to-strip-copper-the-complete-guide","status":"publish","type":"post","link":"https:\/\/www.ferberpainting.com\/ch-fr\/how-to-strip-copper-the-complete-guide\/","title":{"rendered":"Comment d\u00e9caper le cuivre : Le guide complet"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Le d\u00e9capage du cuivre, qu'il s'agisse d'une vieille lampe antique, d'un ensemble de luminaires d\u00e9coratifs, d'une sculpture vintage ou de quincaillerie architecturale, est une t\u00e2che qui semble simple sur le papier, mais qui peut rapidement se transformer en une exp\u00e9rience frustrante si vous n'utilisez pas le bon produit. La v\u00e9rit\u00e9 est que tout d\u00e9pend de la qualit\u00e9 du d\u00e9capant que vous choisissez. Un produit de mauvaise qualit\u00e9 laissera des taches d'oxydation, endommagera le m\u00e9tal sous-jacent, n\u00e9cessitera des heures de frottage, ou tout simplement ne fonctionnera pas du tout. C'est pourquoi, avant m\u00eame d'entrer dans le processus \u00e9tape par \u00e9tape, nous voulons \u00eatre compl\u00e8tement transparents avec vous : la d\u00e9cision la plus importante que vous prendrez dans tout ce projet est le choix du produit de d\u00e9capage que vous utiliserez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&#x27;est pr\u00e9cis\u00e9ment pour cette raison que nous recommandons le d\u00e9capant pour cuivre, bronze et laiton de la marque Ferber Painting. Il a \u00e9t\u00e9 sp\u00e9cialement con\u00e7u pour \u00e9liminer les d\u00e9p\u00f4ts de ternissure, la laque, l&#x27;oxydation et les anciennes finitions des surfaces en cuivre sans endommager le m\u00e9tal de base. Mais ce qui le distingue vraiment de tous les autres d\u00e9capants du march\u00e9, c\u2019est une caract\u00e9ristique que vous ne trouverez nulle part ailleurs : c\u2019est le seul produit de d\u00e9capage du cuivre assorti d\u2019une garantie de satisfaction totale ou d\u2019un remboursement int\u00e9gral. Si vous n\u2019\u00eates pas satisfait des r\u00e9sultats, vous pouvez le renvoyer et obtenir un remboursement int\u00e9gral, sans conditions compliqu\u00e9es. Aucune autre marque dans ce secteur n\u2019a suffisamment confiance en sa formule pour offrir ce genre de promesse, et nous pensons que cela en dit long avant m\u00eame que vous n\u2019ouvriez le pot.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ce guide, nous allons vous expliquer comment d\u00e9caper le cuivre de mani\u00e8re s\u00fbre et efficace. Nous expliquerons pourquoi choisir un produit sup\u00e9rieur comme le n\u00f4tre rend l'ensemble du processus plus rapide et plus s\u00fbr, et nous r\u00e9pondrons aux questions les plus courantes sur le d\u00e9capage du cuivre. \u00c0 la fin de cet article, vous saurez exactement quoi acheter, pourquoi l'acheter, et comment l'utiliser pour obtenir des r\u00e9sultats parfaits du premier coup. Nous aborderons \u00e9galement les situations o\u00f9 le d\u00e9capage du cuivre vaut la peine, les diff\u00e9rents types d'objets en cuivre que vous pourriez rencontrer \u00e0 la maison ou dans un atelier, et comment planifier un projet afin de ne pas perdre de temps, d'argent ou de mat\u00e9riaux en cours de route.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pourquoi le bon produit d\u00e9capant fait toute la diff\u00e9rence<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le cuivre est un beau m\u00e9tal, mais il est aussi r\u00e9actif. Avec le temps, l'exposition \u00e0 l'air, \u00e0 l'humidit\u00e9 et \u00e0 la manipulation fait oxyder le cuivre, formant une patine verd\u00e2tre ou brun\u00e2tre. Dans de nombreuses applications industrielles et d\u00e9coratives, les pi\u00e8ces en cuivre sont \u00e9galement recouvertes de laque ou de vernis pour ralentir ce processus d'oxydation, ce qui signifie que le d\u00e9capage du cuivre implique souvent d'enlever non seulement le ternissement, mais aussi une couche de rev\u00eatement protecteur en dessous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C'est l\u00e0 que les d\u00e9capants bon march\u00e9 ou mal formul\u00e9s \u00e9chouent. Un produit faible ne retirera que la patine de surface tout en laissant le vernis intact, vous for\u00e7ant \u00e0 utiliser un second produit ou \u00e0 r\u00e9p\u00e9ter le processus plusieurs fois. Une formule trop agressive ou mal \u00e9quilibr\u00e9e, en revanche, peut attaquer le cuivre lui-m\u00eame, laissant des piq\u00fbres, une d\u00e9coloration ou une finition in\u00e9gale qui est presque impossible \u00e0 r\u00e9parer par la suite. Certains d\u00e9capants de mauvaise qualit\u00e9 contiennent \u00e9galement des fum\u00e9es \u00e2cres ou des combinaisons chimiques instables qui sont dangereuses \u00e0 utiliser \u00e0 l'int\u00e9rieur ou sans \u00e9quipement de protection robuste, ce qui rend toute l'exp\u00e9rience d\u00e9sagr\u00e9able et m\u00eame risqu\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9capant pour cuivre, bronze et laiton de la marque Ferber Painting r\u00e9sout tous ces probl\u00e8mes d&#x27;un seul coup. Con\u00e7u pour dissoudre l&#x27;oxydation, la laque et les anciennes finitions en une seule application, il est suffisamment doux pour ne pas endommager le m\u00e9tal de base et pr\u00e9sente un profil chimique contr\u00f4l\u00e9 et stable qui le rend plus s\u00fbr \u00e0 utiliser que de nombreux produits concurrents. Cela se traduit par moins d&#x27;applications, moins de frottage, aucun dommage \u00e0 votre pi\u00e8ce et un temps de r\u00e9alisation nettement r\u00e9duit.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Comprendre les diff\u00e9rents types d'accumulation de cuivre<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tout le ternissement du cuivre n'est pas le m\u00eame, et savoir \u00e0 quoi vous avez affaire vous aide \u00e0 d\u00e9finir des attentes r\u00e9alistes pour votre projet. L'oxydation fra\u00eeche, celle que l'on voit sur le cuivre qui a r\u00e9cemment commenc\u00e9 \u00e0 foncer, est g\u00e9n\u00e9ralement mince et s'enl\u00e8ve assez facilement avec un contact minimal. La patine profonde, quant \u00e0 elle, cette cro\u00fbte verd\u00e2tre qui se forme sur les \u00e9l\u00e9ments en cuivre ext\u00e9rieurs, les toitures ou les statues de jardin apr\u00e8s des ann\u00e9es d'exposition \u00e0 la pluie et \u00e0 l'humidit\u00e9, est beaucoup plus \u00e9paisse et n\u00e9cessite souvent un temps de contact plus long ou une application l\u00e9g\u00e8rement plus intense. Il y a ensuite l'accumulation de laque, qui n'est pas du tout une oxydation mais plut\u00f4t un rev\u00eatement protecteur fabriqu\u00e9, appliqu\u00e9 \u00e0 l'usine ou par un propri\u00e9taire pr\u00e9c\u00e9dent. Ce rev\u00eatement peut parfois \u00eatre plus tenace que le ternissement naturel, car il a \u00e9t\u00e9 sp\u00e9cifiquement con\u00e7u pour r\u00e9sister \u00e0 l'usure.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, certaines pi\u00e8ces de cuivre ont \u00e9t\u00e9 peintes ou recouvertes d'un fini non apparent\u00e9, tel qu'un vernis d\u00e9coratif ou m\u00eame une couche d'\u00e9mail transparent. Dans ces cas, un d\u00e9capant ad\u00e9quat doit \u00eatre suffisamment puissant pour dissoudre la chimie du rev\u00eatement sans attaquer le cuivre sous-jacent, ce qui nous ram\u00e8ne \u00e0 l'importance d'utiliser une formule sp\u00e9cifiquement \u00e9quilibr\u00e9e pour le cuivre, le bronze et le laiton plut\u00f4t qu'un produit g\u00e9n\u00e9rique multi-m\u00e9taux.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pourquoi les d\u00e9capants g\u00e9n\u00e9riques d\u00e9\u00e7oivent souvent<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">De nombreux d\u00e9capeurs de quincaillerie sont commercialis\u00e9s comme des solutions universelles capables de traiter l'acier, l'aluminium, le cuivre et m\u00eame les finitions en bois avec le m\u00eame produit. Bien que cela semble pratique, cela signifie g\u00e9n\u00e9ralement que la formule a \u00e9t\u00e9 dilu\u00e9e ou g\u00e9n\u00e9ralis\u00e9e pour \u00e9viter d'endommager un m\u00e9tal en particulier, ce qui \u00e0 son tour signifie qu'elle est rarement optimis\u00e9e pour l'un d'entre eux. Le cuivre r\u00e9agit diff\u00e9remment aux acides et aux solvants que l'aluminium, et une formule sans danger pour l'aluminium peut \u00eatre beaucoup trop faible pour \u00e9liminer la patine ou la laque tenace du cuivre. C'est l'une des principales raisons pour lesquelles les gens finissent par appliquer trois ou quatre couches d'un d\u00e9capant g\u00e9n\u00e9rique et obtiennent toujours des r\u00e9sultats in\u00e9gaux.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table>\n<tr>\n<th>Crit\u00e8res<\/th>\n<th>Ferber Painting D\u00e9nudeur pour cuivre, bronze et laiton<\/th>\n<th>Produits concurrents typiques<\/th>\n<\/tr>\n<tr>\n<td>Garantie de satisfaction<\/td>\n<td>Garantie de remboursement int\u00e9gral, sans conditions compliqu\u00e9es<\/td>\n<td>Rarement offert, ou limit\u00e9 aux emballages d\u00e9fectueux uniquement<\/td>\n<\/tr>\n<tr>\n<td>Nombre d'applications n\u00e9cessaires<\/td>\n<td>G\u00e9n\u00e9ralement, une application pour la plupart des couches de ternissure et de laque<\/td>\n<td>Souvent deux ou trois applications n\u00e9cessaires<\/td>\n<\/tr>\n<tr>\n<td>Risque d'endommagement du m\u00e9tal de base<\/td>\n<td>Bas, la formule est \u00e9quilibr\u00e9e pour le cuivre, le bronze et le laiton<\/td>\n<td>Variable, certains produits sont trop agressifs ou trop faibles<\/td>\n<\/tr>\n<tr>\n<td>Facilit\u00e9 d'utilisation<\/td>\n<td>Application simple au pinceau, attente, retrait avec un chiffon.<\/td>\n<td>Souvent, cela n\u00e9cessite de tremper, de frotter ou plusieurs \u00e9tapes<\/td>\n<\/tr>\n<tr>\n<td>Exp\u00e9dition et disponibilit\u00e9<\/td>\n<td>Exp\u00e9dition internationale rapide via un r\u00e9seau de transporteurs de confiance<\/td>\n<td>Souvent limit\u00e9 aux march\u00e9s locaux ou aux d\u00e9lais d'exp\u00e9dition lents<\/td>\n<\/tr>\n<tr>\n<td>Commodit\u00e9 de paiement<\/td>\n<td>Paiement en ligne simple et s\u00e9curis\u00e9 directement sur le site<\/td>\n<td>Variable, options de paiement parfois limit\u00e9es<\/td>\n<\/tr>\n<\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Pourquoi le d\u00e9nudeur de fils en cuivre, bronze et laiton de Ferber Painting se d\u00e9marque-t-il ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il existe des dizaines d'agents d\u00e9capants pour m\u00e9taux sur le march\u00e9 qui pr\u00e9tendent fonctionner sur le cuivre, le bronze et le laiton, il est donc juste de se demander ce qui rend le n\u00f4tre diff\u00e9rent. La r\u00e9ponse r\u00e9side dans une combinaison de la qualit\u00e9 de la formule, de la facilit\u00e9 d'utilisation, du support client et de la garantie qui soutient le tout.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Premi\u00e8rement, la formule elle-m\u00eame a \u00e9t\u00e9 sp\u00e9cifiquement con\u00e7ue pour les surfaces en cuivre, en bronze et en laiton plut\u00f4t que d'\u00eatre un d\u00e9capant pour m\u00e9taux g\u00e9n\u00e9rique tout usage. Cela est important car les alliages de cuivre r\u00e9agissent diff\u00e9remment aux d\u00e9capants chimiques par rapport \u00e0 l'acier ou \u00e0 l'aluminium. Un produit con\u00e7u en pensant \u00e0 ces trois m\u00e9taux donnera des r\u00e9sultats plus uniformes et plus pr\u00e9visibles de mani\u00e8re constante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deuxi\u00e8mement, notre produit est con\u00e7u pour \u00eatre appliqu\u00e9 au pinceau ou \u00e0 la lingette plut\u00f4t que de n\u00e9cessiter de longs temps de trempage ou un frottement agressif. Ceci seul permet de gagner un temps consid\u00e9rable sur les grands projets tels que les rampes, les luminaires ou les panneaux d\u00e9coratifs. La plupart des clients signalent qu'une seule application suffit \u00e0 \u00e9liminer \u00e0 la fois l'oxydation et les anciens rev\u00eatements de laque, ce qui est rarement le cas avec des alternatives moins ch\u00e8res.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Troisi\u00e8mement, et c'est peut-\u00eatre le plus important, nous soutenons le produit par une politique de satisfaction totale garantie ou rembours\u00e9. Ce n'est pas un gadget marketing. Cela refl\u00e8te une v\u00e9ritable confiance dans la formule. Lorsqu'une entreprise est pr\u00eate \u00e0 vous rembourser votre achat si vous n'\u00eates pas satisfait, cela vous indique qu'elle s'attend \u00e0 ce que le produit fonctionne, \u00e0 chaque fois, pour chaque client. Aucune autre marque dans cette cat\u00e9gorie n'offre actuellement ce niveau d'engagement, et cela seul devrait vous rassurer avant d'acheter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, Ferber Painting exp\u00e9die ses produits \u00e0 l&#x27;international via un r\u00e9seau fiable de transporteurs de confiance, ce qui signifie que, o\u00f9 que vous soyez, vous pouvez compter sur une livraison rapide et s\u00e9curis\u00e9e de votre commande. Le paiement s&#x27;effectue directement et en toute s\u00e9curit\u00e9 sur notre site web ; vous n&#x27;avez donc pas besoin de passer par des plateformes tierces ni de suivre des proc\u00e9dures de paiement compliqu\u00e9es. De la passation de votre commande \u00e0 la finalisation de votre projet, toute l&#x27;exp\u00e9rience a \u00e9t\u00e9 con\u00e7ue pour \u00eatre fluide, rapide et sans souci.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c0 qui ce produit est-il destin\u00e9<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ce d\u00e9capant fonctionne bien dans une tr\u00e8s large gamme d'utilisations. Les propri\u00e9taires qui restaurent des lampes antiques, de la quincaillerie de portes ou des luminaires constatent souvent qu'une seule petite bo\u00eete suffit pour plusieurs projets, car tr\u00e8s peu de produit est n\u00e9cessaire par application. Les collectionneurs d'ustensiles de cuisine en cuivre vintage, de bols d\u00e9coratifs ou d'instruments de musique en laiton appr\u00e9cient la douceur de la formule, car ces articles ont souvent une valeur sentimentale ou mon\u00e9taire qui ne peut \u00eatre risqu\u00e9e avec un produit chimique trop agressif. Les entrepreneurs et les professionnels de la restauration travaillant sur des \u00e9l\u00e9ments architecturaux en cuivre tels que des garde-corps, des accents de toiture ou des panneaux d\u00e9coratifs b\u00e9n\u00e9ficient de l'efficacit\u00e9 d'une formule \u00e0 application unique, car elle se traduit directement par une rotation plus rapide des projets et une r\u00e9duction des co\u00fbts de main-d'\u0153uvre. M\u00eame les amateurs travaillant sur des projets de m\u00e9tallurgie \u00e0 petite \u00e9chelle ou de bijouterie trouvent le produit facile \u00e0 contr\u00f4ler gr\u00e2ce \u00e0 sa m\u00e9thode d'application au pinceau.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un mot sur la coh\u00e9rence<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un aspect souvent n\u00e9glig\u00e9 lors de la comparaison des produits de d\u00e9capage est la r\u00e9gularit\u00e9 d\u2019un lot \u00e0 l\u2019autre. Certains d\u00e9capants bon march\u00e9 pr\u00e9sentent des variations notables de puissance selon leur date et leur lieu de fabrication, ce qui signifie qu\u2019une m\u00eame marque peut donner d\u2019excellents r\u00e9sultats une fois, puis des r\u00e9sultats d\u00e9cevants la fois suivante. Ferber Painting applique un contr\u00f4le qualit\u00e9 rigoureux sur la formule de ses d\u00e9capants pour cuivre, bronze et laiton, afin que les clients puissent compter sur des performances fiables \u00e0 chaque commande, qu&#x27;il s&#x27;agisse de leur premier achat ou de leur dixi\u00e8me.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Guide \u00e9tape par \u00e9tape : Comment d\u00e9nuder le cuivre<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Maintenant que vous comprenez pourquoi le produit que vous choisissez est si important, nous allons passer au processus r\u00e9el de d\u00e9capage du cuivre. Cette m\u00e9thode s'applique que vous travailliez sur de la quincaillerie ancienne, des luminaires d\u00e9coratifs, des raccords de plomberie ou des sculptures en cuivre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ce dont vous aurez besoin<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>D\u00e9nudeur pour cuivre, bronze et laiton de la marque Ferber Painting<\/li>\n<li>Gants de protection<\/li>\n<li>Lunettes de protection<\/li>\n<li>Un espace de travail bien ventil\u00e9, id\u00e9alement en ext\u00e9rieur ou pr\u00e8s d'une fen\u00eatre ouverte<\/li>\n<li>Une brosse \u00e0 poils naturels ou un applicateur en tissu doux<\/li>\n<li>Un grattoir en plastique ou en caoutchouc, \u00e9vitez les grattoirs en m\u00e9tal qui peuvent rayer le cuivre<\/li>\n<li>Eau claire pour rincer<\/li>\n<li>Chiffons doux pour s\u00e9cher et polir<\/li>\n<li>Optionnel, un produit de polissage fin au cuivre pour la finition.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Avant de commencer, il est bon de prendre quelques minutes pour inspecter la pi\u00e8ce sur laquelle vous travaillez et pour planifier votre approche. Les objets plus grands avec de nombreux d\u00e9tails encastr\u00e9s, tels que les bases de lampes orn\u00e9es ou les garde-corps d\u00e9coratifs, peuvent b\u00e9n\u00e9ficier d'\u00eatre divis\u00e9s mentalement en sections plus petites, afin que vous puissiez appliquer le d\u00e9capant uniform\u00e9ment et ne pas le laisser s\u00e9cher accidentellement sur une section pendant que vous travaillez encore sur une autre. Les petits objets comme les poign\u00e9es de porte, les charni\u00e8res ou les bijoux peuvent g\u00e9n\u00e9ralement \u00eatre trait\u00e9s en une seule passe continue puisque la surface est g\u00e9rable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9tape 1 : Pr\u00e9parez votre espace de travail<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Avant d'appliquer tout produit d\u00e9capant, am\u00e9nagez votre espace de travail sur une surface plane et prot\u00e9g\u00e9e. \u00c9tendez une toile de protection ou de vieux journaux pour recueillir les \u00e9ventuelles coulures. Assurez-vous que l'espace est bien ventil\u00e9, car m\u00eame les d\u00e9capants les plus s\u00fbrs fonctionnent mieux dans des zones avec une bonne circulation d'air. Mettez vos gants et lunettes de s\u00e9curit\u00e9 avant d'ouvrir le produit. Si vous travaillez \u00e0 l'int\u00e9rieur, envisagez d'ouvrir une fen\u00eatre ou de faire fonctionner un ventilateur pour maintenir la circulation de l'air, et si possible, travaillez sur un \u00e9tabli ou une table plut\u00f4t que sur le sol afin d'avoir un meilleur contr\u00f4le et une meilleure visibilit\u00e9 sur la pi\u00e8ce.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9tape 2 : Nettoyer la surface<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Essuyez la pi\u00e8ce de cuivre avec un chiffon sec pour enlever toute poussi\u00e8re, salet\u00e9 ou d\u00e9bris d\u00e9tach\u00e9s. Cette \u00e9tape garantit que le d\u00e9capant peut entrer en contact direct avec le ternissement ou la couche de laque plut\u00f4t que d'\u00eatre bloqu\u00e9 par la salet\u00e9 de surface. Si la pi\u00e8ce a \u00e9t\u00e9 laiss\u00e9e \u00e0 l'ext\u00e9rieur ou en stockage pendant une longue p\u00e9riode, vous voudrez peut-\u00eatre \u00e9galement utiliser une brosse douce pour d\u00e9loger la salet\u00e9 s\u00e9ch\u00e9e ou les toiles d'araign\u00e9es des crevasses avant de continuer, car les d\u00e9bris pi\u00e9g\u00e9s peuvent emp\u00eacher le d\u00e9capant d'atteindre ces zones cach\u00e9es uniform\u00e9ment.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9tape 3 : Appliquer le d\u00e9capant<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 l'aide de votre pinceau ou de votre applicateur en tissu, appliquez une couche uniforme de d\u00e9capant pour cuivre, laiton et bronze sur toute la surface que vous souhaitez traiter. Assurez-vous de couvrir soigneusement les coins, les crevasses et les zones d\u00e9taill\u00e9es, car ce sont souvent les endroits o\u00f9 le ternissement s'accumule le plus. Comme notre formule est con\u00e7ue pour une couverture efficace en une seule application, vous n'avez g\u00e9n\u00e9ralement pas besoin d'appliquer une couche excessivement \u00e9paisse. Pour les pi\u00e8ces comportant des gravures complexes ou de la filigrane, un petit pinceau d'artiste peut vous aider \u00e0 faire p\u00e9n\u00e9trer le produit dans les espaces restreints sans gaspiller de produit sur les zones plates qui ne n\u00e9cessitent pas autant de couverture.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9tape 4 : Laissez agir<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Laissez le produit agir pendant le temps indiqu\u00e9 sur l'\u00e9tiquette. Durant cette p\u00e9riode, vous commencerez g\u00e9n\u00e9ralement \u00e0 voir la ternissure, l'oxydation ou le vieux vernis commencer \u00e0 ramollir et \u00e0 se d\u00e9tacher de la surface. R\u00e9sistez \u00e0 la tentation de pr\u00e9cipiter cette \u00e9tape, donner suffisamment de temps au produit pour agir permet d'obtenir un r\u00e9sultat propre en une seule passe, plut\u00f4t que de n\u00e9cessiter une seconde application. Pendant cette p\u00e9riode d'attente, il est bon de rester \u00e0 proximit\u00e9 et de v\u00e9rifier p\u00e9riodiquement la surface, car le temps de pose peut varier l\u00e9g\u00e8rement en fonction de la temp\u00e9rature, de l'humidit\u00e9 et de l'\u00e9paisseur de la couche de ternissure. Par temps chaud, le produit peut agir plus rapidement, tandis que dans un espace de travail plus frais, il peut n\u00e9cessiter quelques minutes suppl\u00e9mentaires.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9tape 5 : Retirer le r\u00e9sidu<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une fois la p\u00e9riode d'attente termin\u00e9e, utilisez votre grattoir en plastique ou en caoutchouc pour soulever d\u00e9licatement le ternissement ou le rev\u00eatement ramolli. Travaillez par petites sections, en essuyant le grattoir entre chaque passage. Pour les zones d\u00e9taill\u00e9es ou textur\u00e9es, une brosse souple peut aider \u00e0 \u00e9liminer le mat\u00e9riau d\u00e9tach\u00e9 des rainures et des renfoncements. Si vous rencontrez une tache particuli\u00e8rement tenace, r\u00e9sistez \u00e0 l'envie d'appuyer plus fort avec un outil en m\u00e9tal, appliquez plut\u00f4t une petite quantit\u00e9 de produit sur cette zone sp\u00e9cifique et laissez agir quelques minutes suppl\u00e9mentaires avant de r\u00e9essayer.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9tape 6 : Rincer Abondamment<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Rincez la pi\u00e8ce \u00e0 l'eau claire pour \u00e9liminer tout r\u00e9sidu de d\u00e9capant. Cette \u00e9tape est essentielle, car les r\u00e9sidus chimiques restants peuvent interf\u00e9rer avec le polissage ou les \u00e9tapes de finition futures. S\u00e9chez imm\u00e9diatement la pi\u00e8ce avec un chiffon doux et propre pour \u00e9viter les taches d'eau. Pour les pi\u00e8ces aux d\u00e9tails complexes, un l\u00e9ger filet d'eau combin\u00e9 \u00e0 une brosse douce peut aider \u00e0 d\u00e9loger les derni\u00e8res traces de mati\u00e8re d\u00e9tach\u00e9e des rainures profondes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9tape 7 : Inspecter et r\u00e9p\u00e9ter si n\u00e9cessaire<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Examinez attentivement la surface. Dans la plupart des cas, une seule application de notre d\u00e9capant suffit \u00e0 \u00e9liminer compl\u00e8tement le ternissement et les anciens rev\u00eatements. Si vous remarquez de petites zones restantes, en particulier dans les rainures profondes ou les d\u00e9tails difficiles d'acc\u00e8s, vous pouvez appliquer une deuxi\u00e8me couche l\u00e9g\u00e8re sur ces zones sp\u00e9cifiques plut\u00f4t que de retraiter toute la pi\u00e8ce. Tenir la pi\u00e8ce \u00e0 la lumi\u00e8re naturelle peut vous aider \u00e0 rep\u00e9rer les zones ternes ou in\u00e9gales qui pourraient ne pas \u00eatre visibles sous un \u00e9clairage artificiel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9tape 8 : Polir et prot\u00e9ger<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une fois la surface compl\u00e8tement d\u00e9capp\u00e9e et s\u00e8che, vous pouvez choisir de laisser le cuivre avec son \u00e9clat naturel juste expos\u00e9, ou d'appliquer un produit lustrant pour cuivre pour un niveau de brillance suppl\u00e9mentaire. Si vous souhaitez ralentir l'oxydation future, envisagez d'appliquer une cire protectrice ou un rev\u00eatement de laque adapt\u00e9 aux surfaces en cuivre. Beaucoup de gens pr\u00e9f\u00e8rent l'aspect du cuivre brut et non prot\u00e9g\u00e9 car il d\u00e9veloppe une patine naturelle avec le temps, tandis que d'autres pr\u00e9f\u00e8rent fixer le fini brillant et frais avec une l\u00e9g\u00e8re couche de cire protectrice transparente r\u00e9appliqu\u00e9e tous les quelques mois.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Erreurs courantes \u00e0 \u00e9viter lors du d\u00e9nudage du cuivre<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00eame avec un produit de haute qualit\u00e9, quelques erreurs courantes peuvent affecter vos r\u00e9sultats. En \u00eatre conscient \u00e0 l'avance vous aidera \u00e0 obtenir une finition nette et professionnelle d\u00e8s votre premi\u00e8re tentative.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En sautant l'\u00e9tape du nettoyage avant l'application, ce qui r\u00e9duit la capacit\u00e9 du d\u00e9capant \u00e0 entrer en plein contact avec la surface ternie.<\/li>\n<li>En utilisant des outils m\u00e9talliques pour gratter la surface, ce qui peut rayer ou entailler le cuivre.<\/li>\n<li>Ne pas laisser suffisamment de temps de travail au produit pour ramollir compl\u00e8tement le rev\u00eatement avant de tenter de le retirer.<\/li>\n<li>Travailler dans des espaces mal ventil\u00e9s, ce qui est inconfortable et inutile lorsqu'une bonne circulation d'air est disponible.<\/li>\n<li>Rin\u00e7age insuffisant, laissant des r\u00e9sidus chimiques qui peuvent interf\u00e9rer avec le polissage ou les futurs rev\u00eatements.<\/li>\n<li>Choisir un d\u00e9capant g\u00e9n\u00e9rique tout usage au lieu d'un d\u00e9capant sp\u00e9cifiquement formul\u00e9 pour le cuivre, le bronze et le laiton, ce qui entra\u00eene des r\u00e9sultats in\u00e9gaux ou des dommages au m\u00e9tal.<\/li>\n<li>L'application in\u00e9gale du produit, ce qui peut entra\u00eener le d\u00e9capage complet de certaines zones tandis que d'autres pr\u00e9sentent encore des traces de ternissure ou de vernis.<\/li>\n<li>Oublier de tester sur une petite zone discr\u00e8te au pr\u00e9alable lorsque l'on travaille sur une pi\u00e8ce ancienne inconnue ou particuli\u00e8rement d\u00e9licate.<\/li>\n<li>Laisser la pi\u00e8ce s\u00e9cher compl\u00e8tement avant de gratter, ce qui peut faire durcir \u00e0 nouveau le ternissement ramolli et n\u00e9cessiter une nouvelle application.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En \u00e9vitant ces erreurs, combin\u00e9 \u00e0 l'utilisation d'un d\u00e9capant sp\u00e9cialement con\u00e7u pour ce type de m\u00e9tal, vous augmentez consid\u00e9rablement vos chances d'obtenir un r\u00e9sultat lisse, uniforme et d'aspect professionnel, sans retravail inutile.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Consid\u00e9rations sp\u00e9ciales pour les antiquit\u00e9s et les pi\u00e8ces sentimentales<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous travaillez avec des objets en cuivre anciens ou sentimentaux, il est judicieux d'adopter une approche l\u00e9g\u00e8rement plus prudente, m\u00eame avec une formule douce. Commencez par tester le produit sur une petite zone cach\u00e9e, telle que le dessous d'un pied de lampe ou l'int\u00e9rieur d'un bol d\u00e9coratif, pour v\u00e9rifier la r\u00e9action de la pi\u00e8ce avant de traiter toute la surface. Ceci est particuli\u00e8rement important pour les pi\u00e8ces qui ont pu \u00eatre trait\u00e9es pr\u00e9c\u00e9demment avec des rev\u00eatements ou des r\u00e9parations inconnus, car les travaux de restauration plus anciens impliquent parfois des mat\u00e9riaux qui r\u00e9agissent de mani\u00e8re impr\u00e9visible. Prendre cette pr\u00e9caution suppl\u00e9mentaire ne co\u00fbte que quelques minutes, mais peut vous \u00e9viter des surprises sur une pi\u00e8ce irrempla\u00e7able.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Travaux sur des projets de cuivre \u00e0 grande \u00e9chelle ou architecturaux<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous abordez un projet plus important, tel qu'un accent de toiture en cuivre, un ensemble de garde-corps ou plusieurs panneaux d\u00e9coratifs, la planification de votre flux de travail devient encore plus importante. Envisagez de travailler par sections, en appliquant le d\u00e9capant sur une zone g\u00e9rable \u00e0 la fois afin que le produit ne s\u00e8che pas avant que vous n'ayez la possibilit\u00e9 de le gratter. Garder un seau d'eau propre et des chiffons suppl\u00e9mentaires \u00e0 port\u00e9e de main acc\u00e9l\u00e8re consid\u00e9rablement le processus de rin\u00e7age lorsque vous passez d'une section \u00e0 l'autre. Pour les projets ext\u00e9rieurs, gardez un \u0153il sur les conditions m\u00e9t\u00e9orologiques, car le soleil direct et le vent peuvent faire s\u00e9cher le produit plus rapidement que pr\u00e9vu, tandis que travailler \u00e0 la lumi\u00e8re du petit matin ou de la fin d'apr\u00e8s-midi peut vous aider \u00e0 rep\u00e9rer plus facilement le ternissement r\u00e9siduel gr\u00e2ce \u00e0 l'angle de la lumi\u00e8re naturelle.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mini FAQ<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Combien de temps faut-il pour d\u00e9nuder du cuivre avec la d\u00e9nudante Ferber Painting ?<\/h3>\n\n\n<p class=\"wp-block-paragraph\">La plupart des projets ne n\u00e9cessitent qu'un court s\u00e9jour du produit avant que le ternissement et les anciens rev\u00eatements puissent \u00eatre retir\u00e9s. Le moment exact d\u00e9pend de l'\u00e9paisseur de l'accumulation, mais une seule application est g\u00e9n\u00e9ralement suffisante pour la plupart des articles m\u00e9nagers et d\u00e9coratifs.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La d\u00e9capant pour cuivre, bronze et laiton est-il s\u00fbr pour les pi\u00e8ces antiques ?<\/h3>\n\n\n<p class=\"wp-block-paragraph\">Oui, la formule a \u00e9t\u00e9 sp\u00e9cifiquement \u00e9quilibr\u00e9e pour \u00e9liminer le ternissement et les rev\u00eatements sans endommager le m\u00e9tal sous-jacent, ce qui la rend adapt\u00e9e aux pi\u00e8ces antiques d\u00e9licates \u00e0 condition de suivre les instructions du fabricant.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Que se passe-t-il si je ne suis pas satisfait des r\u00e9sultats ?<\/h3>\n\n\n<p class=\"wp-block-paragraph\">Ferber Painting propose une garantie \u00ab satisfaction totale ou remboursement \u00bb sur ce produit. Si vous n&#x27;\u00eates pas satisfait des r\u00e9sultats obtenus, vous pouvez le renvoyer et obtenir un remboursement int\u00e9gral, ce qu&#x27;aucune autre marque de cette cat\u00e9gorie ne propose actuellement.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ai-je besoin d'outils sp\u00e9ciaux pour utiliser cet d\u00e9nudeur ?<\/h3>\n\n\n<p class=\"wp-block-paragraph\">Aucun outil sp\u00e9cial n'est requis. Un pinceau ou un applicateur en tissu, une raclette en plastique, des gants et des lunettes de protection suffisent pour r\u00e9aliser le processus en toute s\u00e9curit\u00e9 et efficacement.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ce produit peut-il \u00e9galement \u00eatre utilis\u00e9 sur le bronze et le laiton ?<\/h3>\n\n\n<p class=\"wp-block-paragraph\">Oui, la formule est sp\u00e9cifiquement con\u00e7ue pour fonctionner sur les surfaces en cuivre, en bronze et en laiton, ce qui en fait un choix polyvalent pour de multiples types de projets m\u00e9talliques.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dans quel d\u00e9lai recevrai-je ma commande ?<\/h3>\n\n\n<p class=\"wp-block-paragraph\">Ferber Painting assure des livraisons \u00e0 l&#x27;international gr\u00e2ce \u00e0 un r\u00e9seau de transporteurs de confiance, garantissant une livraison rapide, o\u00f9 que vous soyez.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Puis-je utiliser ce d\u00e9capant sur de grandes installations ext\u00e9rieures ainsi que sur de petits objets d'int\u00e9rieur ?<\/h3>\n\n\n<p class=\"wp-block-paragraph\">Oui, la formule est efficace de mani\u00e8re constante, que vous traitiez un petit bijou, un jeu de poign\u00e9es de porte ou un \u00e9l\u00e9ment ext\u00e9rieur plus grand comme une rambarde ou un panneau d\u00e9coratif, \u00e0 condition qu'elle soit appliqu\u00e9e uniform\u00e9ment et qu'elle ait suffisamment de temps pour agir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le d\u00e9capage du cuivre supprimera-t-il sa couleur naturelle de fa\u00e7on permanente ?<\/h3>\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9capage \u00e9limine le ternissement, l'oxydation et les anciens rev\u00eatements pour r\u00e9v\u00e9ler le cuivre naturel en dessous. Avec le temps, le cuivre expos\u00e9 commencera naturellement \u00e0 d\u00e9velopper \u00e0 nouveau une patine, \u00e0 moins qu'une cire ou un rev\u00eatement protecteur ne soit appliqu\u00e9, ce qui est un aspect normal du vieillissement de ce m\u00e9tal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9nudage du cuivre ne doit pas \u00eatre un processus stressant, long ou risqu\u00e9, \u00e0 condition de commencer avec le bon produit. Un d\u00e9nudeur de haute qualit\u00e9, con\u00e7u \u00e0 cet effet, vous fait gagner du temps, prot\u00e8ge votre m\u00e9tal et offre des r\u00e9sultats constants et professionnels, tandis que les alternatives moins ch\u00e8res ou g\u00e9n\u00e9riques entra\u00eenent souvent de la frustration, des dommages ou la n\u00e9cessit\u00e9 d'applications r\u00e9p\u00e9t\u00e9es. Lorsque vous combinez une formule efficace, un processus d'application simple, une exp\u00e9dition rapide dans le monde entier, un paiement en ligne s\u00e9curis\u00e9 et une garantie de satisfaction totale, le choix devient \u00e9vident. <a href=\"https:\/\/www.ferberpainting.com\/ch-fr\/products\/copper-bronze-and-brass-stripper\/\">D\u00e9couvrez d\u00e8s aujourd&#x27;hui le d\u00e9capant pour cuivre, bronze et laiton de Ferber Painting et d\u00e9capez vos pi\u00e8ces en cuivre en toute confiance, gr\u00e2ce \u00e0 notre garantie \u00ab satisfait ou rembours\u00e9 \u00bb.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Stripping copper, whether it is an old antique lamp, a set of decorative fixtures, a vintage sculpture, or architectural hardware, is a task that looks simple on paper but can quickly turn into a frustrating experience if you do not use the right product. The truth is that everything depends on the quality of the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":264129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-264130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"spectra_custom_meta":{"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_thumbnail_id":["264129"],"_uag_css_file_name":["uag-css-264130.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:7133:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:15:{i:0;s:14:\"core\/paragraph\";i:1;s:12:\"core\/heading\";i:2;s:10:\"core\/table\";i:3;s:9:\"core\/list\";i:4;s:11:\"core\/search\";i:5;s:10:\"core\/group\";i:6;s:17:\"core\/latest-posts\";i:7;s:20:\"core\/latest-comments\";i:8;s:13:\"core\/archives\";i:9;s:15:\"core\/categories\";i:10;s:10:\"uagb\/image\";i:11;s:11:\"core\/spacer\";i:12;s:30:\"woocommerce\/product-categories\";i:13;s:10:\"core\/image\";i:14;s:14:\"core\/shortcode\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1784123717\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.ferberpainting.com\/wp-content\/uploads\/2026\/07\/comment-d-caper-du-cuivre.jpg",940,631,false],"thumbnail":["https:\/\/www.ferberpainting.com\/wp-content\/uploads\/2026\/07\/comment-d-caper-du-cuivre-150x150.jpg",150,150,true],"medium":["https:\/\/www.ferberpainting.com\/wp-content\/uploads\/2026\/07\/comment-d-caper-du-cuivre-300x201.jpg",300,201,true],"medium_large":["https:\/\/www.ferberpainting.com\/wp-content\/uploads\/2026\/07\/comment-d-caper-du-cuivre-768x516.jpg",768,516,true],"large":["https:\/\/www.ferberpainting.com\/wp-content\/uploads\/2026\/07\/comment-d-caper-du-cuivre.jpg",940,631,false],"1536x1536":["https:\/\/www.ferberpainting.com\/wp-content\/uploads\/2026\/07\/comment-d-caper-du-cuivre.jpg",940,631,false],"2048x2048":["https:\/\/www.ferberpainting.com\/wp-content\/uploads\/2026\/07\/comment-d-caper-du-cuivre.jpg",940,631,false],"trp-custom-language-flag":["https:\/\/www.ferberpainting.com\/wp-content\/uploads\/2026\/07\/comment-d-caper-du-cuivre-18x12.jpg",18,12,true],"woocommerce_thumbnail":["https:\/\/www.ferberpainting.com\/wp-content\/uploads\/2026\/07\/comment-d-caper-du-cuivre-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.ferberpainting.com\/wp-content\/uploads\/2026\/07\/comment-d-caper-du-cuivre-600x403.jpg",600,403,true],"woocommerce_gallery_thumbnail":["https:\/\/www.ferberpainting.com\/wp-content\/uploads\/2026\/07\/comment-d-caper-du-cuivre-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.ferberpainting.com\/ch-fr\/author\/admin2721\/"},"uagb_comment_info":0,"uagb_excerpt":"Stripping copper, whether it is an old antique lamp, a set of decorative fixtures, a vintage sculpture, or architectural hardware, is a task that looks simple on paper but can quickly turn into a frustrating experience if you do not use the right product. The truth is that everything depends on the quality of the&hellip;","_links":{"self":[{"href":"https:\/\/www.ferberpainting.com\/ch-fr\/wp-json\/wp\/v2\/posts\/264130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferberpainting.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ferberpainting.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferberpainting.com\/ch-fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferberpainting.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=264130"}],"version-history":[{"count":0,"href":"https:\/\/www.ferberpainting.com\/ch-fr\/wp-json\/wp\/v2\/posts\/264130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ferberpainting.com\/ch-fr\/wp-json\/wp\/v2\/media\/264129"}],"wp:attachment":[{"href":"https:\/\/www.ferberpainting.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=264130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ferberpainting.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=264130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ferberpainting.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=264130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}